{"id":819,"date":"2020-06-10T07:40:56","date_gmt":"2020-06-10T07:40:56","guid":{"rendered":"http:\/\/extrusol.com\/project\/pvf-badajoz-20-mwp\/"},"modified":"2020-06-10T07:40:56","modified_gmt":"2020-06-10T07:40:56","slug":"pvf-badajoz-20-mwp","status":"publish","type":"project","link":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/","title":{"rendered":"PVF Badajoz &#8211; 20 MWp"},"content":{"rendered":"<h2>PVF Badajoz<\/h2>\n<p>Montaje\u00a0de Estructura y \u00a0M\u00f3dulos<\/p>\n<p><strong>20,00 MWp<\/strong><\/p>\n<h4>2019<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>PVF Badajoz Montaje\u00a0de Estructura y \u00a0M\u00f3dulos 20,00 MWp 2019<\/p>\n","protected":false},"author":9,"featured_media":413,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"project_category":[16],"project_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PVF Badajoz - 20 MWp - Extrusol<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PVF Badajoz - 20 MWp - Extrusol\" \/>\n<meta property=\"og:description\" content=\"PVF Badajoz Montaje\u00a0de Estructura y \u00a0M\u00f3dulos 20,00 MWp 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/\" \/>\n<meta property=\"og:site_name\" content=\"Extrusol\" \/>\n<meta property=\"og:image\" content=\"https:\/\/extrusol.com\/wp-content\/uploads\/2019\/12\/IMG_6006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1512\" \/>\n\t<meta property=\"og:image:height\" content=\"2016\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/extrusol.com\/#website\",\"url\":\"https:\/\/extrusol.com\/\",\"name\":\"Extrusol\",\"description\":\"Extrusol construye proyectos de energ\\u00eda solar fotovoltaica, para ello cuenta con medios mec\\u00e1nicos propios.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/extrusol.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/extrusol.com\/wp-content\/uploads\/2019\/12\/IMG_6006.jpg\",\"contentUrl\":\"https:\/\/extrusol.com\/wp-content\/uploads\/2019\/12\/IMG_6006.jpg\",\"width\":1512,\"height\":2016},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#webpage\",\"url\":\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/\",\"name\":\"PVF Badajoz - 20 MWp - Extrusol\",\"isPartOf\":{\"@id\":\"https:\/\/extrusol.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#primaryimage\"},\"datePublished\":\"2020-06-10T07:40:56+00:00\",\"dateModified\":\"2020-06-10T07:40:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/extrusol.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\/\/extrusol.com\/project\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PVF Badajoz &#8211; 20 MWp\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PVF Badajoz - 20 MWp - Extrusol","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/","og_locale":"en_US","og_type":"article","og_title":"PVF Badajoz - 20 MWp - Extrusol","og_description":"PVF Badajoz Montaje\u00a0de Estructura y \u00a0M\u00f3dulos 20,00 MWp 2019","og_url":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/","og_site_name":"Extrusol","og_image":[{"width":1512,"height":2016,"url":"https:\/\/extrusol.com\/wp-content\/uploads\/2019\/12\/IMG_6006.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/extrusol.com\/#website","url":"https:\/\/extrusol.com\/","name":"Extrusol","description":"Extrusol construye proyectos de energ\u00eda solar fotovoltaica, para ello cuenta con medios mec\u00e1nicos propios.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/extrusol.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#primaryimage","inLanguage":"en-US","url":"https:\/\/extrusol.com\/wp-content\/uploads\/2019\/12\/IMG_6006.jpg","contentUrl":"https:\/\/extrusol.com\/wp-content\/uploads\/2019\/12\/IMG_6006.jpg","width":1512,"height":2016},{"@type":"WebPage","@id":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#webpage","url":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/","name":"PVF Badajoz - 20 MWp - Extrusol","isPartOf":{"@id":"https:\/\/extrusol.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#primaryimage"},"datePublished":"2020-06-10T07:40:56+00:00","dateModified":"2020-06-10T07:40:56+00:00","breadcrumb":{"@id":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/extrusol.com\/en\/project\/pvf-badajoz-20-mwp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/extrusol.com\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/extrusol.com\/project\/"},{"@type":"ListItem","position":3,"name":"PVF Badajoz &#8211; 20 MWp"}]}]}},"_links":{"self":[{"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/project\/819"}],"collection":[{"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":0,"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/project\/819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/media\/413"}],"wp:attachment":[{"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/project_category?post=819"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/extrusol.com\/en\/wp-json\/wp\/v2\/project_tag?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}